{"id":64295,"date":"2025-08-07T08:14:44","date_gmt":"2025-08-07T06:14:44","guid":{"rendered":"https:\/\/at3w.com\/?p=64295"},"modified":"2025-08-07T08:14:44","modified_gmt":"2025-08-07T06:14:44","slug":"coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation","status":"publish","type":"post","link":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/","title":{"rendered":"S\u00e9curit\u00e9 face aux orages \u2013 Que faire apr\u00e8s l&rsquo;impact de la foudre sur un paratonnerre ?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-flat ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#Quest-ce_quun_systeme_de_protection_contre_la_foudre\" >Qu&rsquo;est-ce qu&rsquo;un syst\u00e8me de protection contre la foudre ?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#Impact_dun_coup_de_foudre_%E2%80%93_Inspection_visuelle_apres_levenement\" >Impact d\u2019un coup de foudre &#8211; Inspection visuelle apr\u00e8s l&rsquo;\u00e9v\u00e9nement<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#Verifications_techniques_et_tests_du_systeme\" >V\u00e9rifications techniques et tests du syst\u00e8me<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#Normes_et_reglementations_concernant_la_maintenance_des_systemes_de_protection_contre_la_foudre_apres_un_impact\" >Normes et r\u00e9glementations concernant la maintenance des syst\u00e8mes de protection contre la foudre apr\u00e8s un impact<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#Noticias_relacionadas\" >Noticias relacionadas<\/a><\/li><\/ul><\/nav><\/div>\n<p>[vc_row][vc_column][vc_column_text]<strong>Un syst\u00e8me de protection contre la foudre emp\u00eache qu\u2019un impact direct ne touche la structure, mais la d\u00e9charge frappe effectivement le paratonnerre. <\/strong><strong>C\u2019est pourquoi, apr\u00e8s un impact, il est essentiel de v\u00e9rifier minutieusement l\u2019ensemble du syst\u00e8me de protection contre la foudre, car l\u2019int\u00e9grit\u00e9 de composants critiques (paratonnerre, conducteurs, connexions, prise de terre, etc.) peut \u00eatre compromise. <\/strong><strong>Suivre un protocole post-impact garantit le bon fonctionnement du syst\u00e8me et le maintien de la protection de l\u2019installation.<\/strong><\/p>\n<p>L\u2019int\u00e9gration de technologies intelligentes permettant de surveiller l\u2019\u00e9tat du syst\u00e8me \u00e0 distance ajoute un niveau de s\u00e9curit\u00e9 suppl\u00e9mentaire, en anticipant les r\u00e9parations au-del\u00e0 des inspections visuelles et des v\u00e9rifications p\u00e9riodiques.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quest-ce_quun_systeme_de_protection_contre_la_foudre\"><\/span><strong>Qu&rsquo;est-ce qu&rsquo;un syst\u00e8me de protection contre la foudre ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Par d\u00e9finition, un syst\u00e8me de protection contre la foudre a pour objectif de capter la foudre, de conduire son courant en toute s\u00e9curit\u00e9 jusqu\u2019\u00e0 la terre, de le dissiper dans le sol et de prot\u00e9ger contre les effets secondaires de la d\u00e9charge.<\/p>\n<p>Les syst\u00e8mes de protection contre la foudre distinguent deux types d\u2019\u00e9l\u00e9ments : les \u00e9l\u00e9ments de protection externe et ceux de protection interne.<br \/>\nLes \u00e9l\u00e9ments de protection externe se composent g\u00e9n\u00e9ralement d\u2019une ou plusieurs t\u00eates captrices (paratonnerres), de deux conducteurs de descente ou plus, et d\u2019un syst\u00e8me de mise \u00e0 la terre.<\/p>\n<h3>Syst\u00e8me de protection contre la foudre : protection externe<\/h3>\n<p>Les paratonnerres \u00e0 dispositif d\u2019amor\u00e7age (PDA) se distinguent par la g\u00e9n\u00e9ration continue d\u2019un traceur ascendant qui intercepte le traceur descendant de la foudre avant toute autre structure dans son rayon d&rsquo;action. Lorsqu\u2019un PDA anticipe davantage la cr\u00e9ation de ce traceur ascendant (c&rsquo;est-\u00e0-dire qu&rsquo;il poss\u00e8de un temps d\u2019avance plus long), il parvient \u00e0 capter le traceur descendant \u00e0 une plus grande distance et prot\u00e8ge ainsi une zone plus large. Le rayon de protection correspondant \u00e0 chaque hauteur est d\u00e9termin\u00e9 en fonction du temps d\u2019avance du paratonnerre et du niveau de protection requis pour chaque structure.<\/p>\n<p>Les paratonnerres de la gamme <a href=\"https:\/\/at3w.com\/fr\/smart-lightning\/paratonnerre-intelligent-dat-controler-remote\/\" target=\"_blank\" rel=\"noopener\"><strong>DAT CONTROLER\u00ae<\/strong><\/a> d&rsquo;Aplicaciones Tecnol\u00f3gicas S.A. int\u00e8grent la derni\u00e8re technologie en dispositifs d\u2019amor\u00e7age. De plus, le paratonnerre intelligent <strong>DAT CONTROLER\u00ae REMOTE<\/strong> dispose d\u2019un autodiagnostic de la t\u00eate captrice et d&rsquo;une communication via IoT des r\u00e9sultats pour garantir le bon fonctionnement de l&rsquo;\u00e9quipement.<\/p>\n<p>Sur la descente du SPF, il est possible d\u2019installer des dispositifs comme le compteur de foudre intelligent <a href=\"https:\/\/at3w.com\/fr\/smart-lightning\/smart-lightning-logger-systeme-intelligent-alerte-enregistrement-temps-reel-coup-foudre-capture\/\" target=\"_blank\" rel=\"noopener\"><strong>SMART LIGHTNING LOGGER<\/strong><\/a> d&rsquo;Aplicaciones Tecnol\u00f3gicas S.A., qui envoie des alertes en temps r\u00e9el lorsqu&rsquo;une d\u00e9charge de foudre est enregistr\u00e9e sur la structure. En plus de l\u2019alerte, le <strong>SMART LIGHTNING LOGGER<\/strong> recueille toutes les informations concernant la d\u00e9charge.<\/p>\n<p>Quant \u00e0 la prise de terre, elle constitue un \u00e9l\u00e9ment essentiel du syst\u00e8me externe de protection contre la foudre, car elle est responsable de dissiper le courant de la d\u00e9charge vers le sol de mani\u00e8re s\u00e9curis\u00e9e. Son efficacit\u00e9 d\u00e9pend de la conductivit\u00e9 du terrain, principalement \u00e9lectrolytique en raison des sels dissous dans l\u2019eau qui l&rsquo;humidifie. Ainsi, cette conductivit\u00e9 peut \u00eatre am\u00e9lior\u00e9e en augmentant la capacit\u00e9 du sol \u00e0 absorber et \u00e0 retenir l&rsquo;eau, ainsi qu\u2019en augmentant la concentration de sels solubles.<\/p>\n<h3>Protection interne &#8211; Protection contre les surtensions<\/h3>\n<p>Un syst\u00e8me interne de protection contre la foudre doit \u00e9galement inclure une installation ad\u00e9quate de <a href=\"https:\/\/at3w.com\/fr\/smart-lightning\/protection-contre-surtensions-transitoires\/\" target=\"_blank\" rel=\"noopener\">protection contre les surtensions<\/a>, ainsi que d&rsquo;autres mesures destin\u00e9es \u00e0 r\u00e9duire les dommages (liaisons \u00e9quipotentielles, blindages, etc.).<\/p>\n<p>Bien que les surtensions transitoires puissent avoir diverses origines, les plus nuisibles proviennent des coups de foudre. Ces pics de tension, extr\u00eamement brefs, atteignent les \u00e9quipements via les r\u00e9seaux d&rsquo;alimentation \u00e9lectrique, de t\u00e9l\u00e9phonie, de t\u00e9l\u00e9vision ou de transmission de donn\u00e9es. La protection contre les surtensions garantit la continuit\u00e9 du service en r\u00e9duisant \u00e0 des niveaux acceptables les risques pour les personnes et les biens. Les dispositifs de protection contre les surtensions (DPS) restent inactifs tant que le signal \u00e9lectrique reste dans ses valeurs normales, mais r\u00e9agissent imm\u00e9diatement face aux pics transitoires en dirigeant le courant de la foudre vers la terre et en prot\u00e9geant ainsi les \u00e9quipements. Une fois le pic absorb\u00e9, le DPS retourne \u00e0 son \u00e9tat de repos.<\/p>\n<p>Il existe trois types de DPS :<\/p>\n<ul>\n<li><strong>Type 1<\/strong> : affrontent la d\u00e9charge directe de la foudre et sont install\u00e9s l\u00e0 o\u00f9 le courant et les effets \u00e9lectromagn\u00e9tiques n&rsquo;ont pas encore \u00e9t\u00e9 att\u00e9nu\u00e9s (tableaux principaux).<\/li>\n<li><strong>Type 2<\/strong> : agissent face aux effets indirects de la foudre, dans des points o\u00f9 l&rsquo;\u00e9nergie a d\u00e9j\u00e0 \u00e9t\u00e9 att\u00e9nu\u00e9e (tableaux secondaires).<\/li>\n<li><strong>Type 3<\/strong> : prot\u00e8gent contre les surtensions r\u00e9siduelles tr\u00e8s faibles et sont plac\u00e9s aussi pr\u00e8s que possible des \u00e9quipements sensibles.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Impact_dun_coup_de_foudre_%E2%80%93_Inspection_visuelle_apres_levenement\"><\/span>Impact d\u2019un coup de foudre &#8211; Inspection visuelle apr\u00e8s l&rsquo;\u00e9v\u00e9nement<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Apr\u00e8s un coup de foudre sur un paratonnerre, il est imp\u00e9ratif de proc\u00e9der rapidement \u00e0 <strong>une inspection visuelle minutieuse<\/strong> de tous les composants visibles du syst\u00e8me de protection contre la foudre. Cette v\u00e9rification initiale a pour but de d\u00e9tecter les dommages \u00e9vidents caus\u00e9s par l&rsquo;intensit\u00e9 de la d\u00e9charge. Il est recommand\u00e9 de v\u00e9rifier les points suivants :<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"><strong>Pointe du paratonnerre<\/strong> <\/span><b>:<\/b><span style=\"font-weight: 400;\"> V\u00e9rifier qu\u2019elle ne pr\u00e9sente pas de d\u00e9formations, de fusion partielle ou de marques de br\u00fblure caus\u00e9es par l&rsquo;impact. Le courant extr\u00eame du coup de foudre peut r\u00e9chauffer la pointe du paratonnerre, et dans des cas graves, le mat\u00e9riau peut fondre en raison de la chaleur. Un paratonnerre endommag\u00e9 doit \u00eatre document\u00e9 et g\u00e9n\u00e9ralement remplac\u00e9 par un mod\u00e8le aux caract\u00e9ristiques identiques.<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Structure et \u00e9l\u00e9ments m\u00e9caniques <\/strong><\/span><b>:<\/b><span style=\"font-weight: 400;\"> revV\u00e9rifier que le m\u00e2t et ses fixations sont intacts et solides, sans desserrages ni corrosion excessive. L&rsquo;impact du coup de foudre peut desserrer des supports ou endommager des ancrages. Il est important de v\u00e9rifier l&rsquo;\u00e9tat m\u00e9canique des colliers\/attaches, des vis et des supports de montage, et de renforcer ou remplacer toute fixation d\u00e9fectueuse.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Conducteurs de descente<\/strong> <\/span><b>:<\/b><span style=\"font-weight: 400;\"> Inspecter le conducteur de descente (le c\u00e2ble rond ou ruban plat reliant le paratonnerre \u00e0 la prise de terre) sur toute sa longueur. S\u2019assurer qu\u2019il <strong>soit continu, sans ruptures ni sections br\u00fbl\u00e9es<\/strong>. Lors de d\u00e9charges tr\u00e8s intenses, le cuivre peut surchauffer et perdre ses propri\u00e9t\u00e9s physiques (r\u00e9sistance m\u00e9canique ou conductivit\u00e9). V\u00e9rifier \u00e9galement les pinces et colliers qui fixent le conducteur \u00e0 la structure, pour s&rsquo;assurer qu&rsquo;ils ne sont pas cass\u00e9s, desserr\u00e9s ou corrod\u00e9s. <strong>Toute pi\u00e8ce endommag\u00e9e doit \u00eatre remplac\u00e9e.<\/strong><\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Liaisons \u00e9quipotentielles <\/strong><\/span><b>:<\/b><span style=\"font-weight: 400;\"> V\u00e9rifier toutes les connexions \u00e9quipotentielles (par exemple, les liaisons avec d&rsquo;autres masses m\u00e9talliques de la structure). Ces connexions <strong>doivent \u00eatre intactes et correctement serr\u00e9es<\/strong>, sans signes de corrosion ni d&rsquo;\u00e9tincelles. Un impact peut provoquer des surtensions affectant ces liaisons, il est donc crucial de v\u00e9rifier <strong>qu\u2019il n\u2019y a pas de dommages ou de s\u00e9parations dans les liaisons<\/strong> qui \u00e9galisent les potentiels. Toute connexion desserr\u00e9e doit \u00eatre r\u00e9ajust\u00e9e, et en cas d\u2019observation de points d\u2019arc \u00e9lectrique ou de zones carbonis\u00e9es, ces \u00e9l\u00e9ments doivent \u00eatre nettoy\u00e9s ou remplac\u00e9s.<\/span><\/li>\n<li><strong>Dispositifs suppl\u00e9mentaires de l&rsquo;installation<\/strong> <b>:<\/b><span style=\"font-weight: 400;\"> Si le syst\u00e8me inclut des dispositifs tels que des <strong>compteurs de foudre<\/strong> (enregistreurs d\u2019impacts) ou des <strong>\u00e9clateurs<\/strong> (gaps d&rsquo;isolement), ils doivent aussi \u00eatre v\u00e9rifi\u00e9s. Par exemple, <strong>lire le compteur de foudre<\/strong> pour v\u00e9rifier s\u2019il a bien enregistr\u00e9 la d\u00e9charge et s\u2019assurer qu\u2019il fonctionne correctement. La pr\u00e9sence d&rsquo;un compteur de foudre permet de conna\u00eetre le nombre de coups de foudre re\u00e7us par le syst\u00e8me et d\u2019aider \u00e0 d\u00e9terminer si des inspections suppl\u00e9mentaires sont n\u00e9cessaires. De plus, toute voie de d\u00e9charge ou dispositif similaire doit \u00eatre inspect\u00e9 pour v\u00e9rifier qu\u2019il n\u2019a pas \u00e9t\u00e9 endommag\u00e9 par une d\u00e9charge lat\u00e9rale.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/li>\n<\/ul>\n<p>Lors de cette inspection visuelle, il est important de <strong>documenter tout dommage ou toute anomalie<\/strong> (pi\u00e8ces manquantes, d\u00e9t\u00e9riorations) par des photos et des notes d\u00e9taill\u00e9es. Tous les <strong>\u00e9l\u00e9ments ext\u00e9rieurs<\/strong> du paratonnerre doivent \u00eatre v\u00e9rifi\u00e9s pour garantir leur int\u00e9grit\u00e9 et leur bon fonctionnement. En r\u00e9sum\u00e9, l\u2019inspection visuelle vise \u00e0 identifier les <strong>dommages physiques visibles<\/strong> sur le capteur, les conducteurs de descente et les liaisons, car ces \u00e9l\u00e9ments permettront de localiser les zones o\u00f9 les coups de foudre ont pu causer des d\u00e9g\u00e2ts.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Verifications_techniques_et_tests_du_systeme\"><\/span>V\u00e9rifications techniques et tests du syst\u00e8me<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Apr\u00e8s une inspection visuelle, des tests techniques doivent \u00eatre r\u00e9alis\u00e9s pour garantir le bon fonctionnement \u00e9lectrique du syst\u00e8me. Ces essais comprennent la v\u00e9rification de la continuit\u00e9 \u00e9lectrique, la mesure de la r\u00e9sistance de terre et le contr\u00f4le des dispositifs de protection associ\u00e9s :<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"><strong>V\u00e9rification du dispositif d\u2019amor\u00e7age (PDA) : <\/strong>\u00c0 l\u2019aide d\u2019un ohmm\u00e8tre ou autre instrument de mesure adapt\u00e9, il convient de v\u00e9rifier que le conducteur de descente pr\u00e9sente une continuit\u00e9 \u00e9lectrique depuis la t\u00eate captrice jusqu\u2019\u00e0 la prise de terre, et que la r\u00e9sistance est faible (proche de z\u00e9ro). Cela confirme que le chemin vers la terre n\u2019a pas \u00e9t\u00e9 interrompu. Selon les normes, la continuit\u00e9 des conducteurs doit \u00eatre correcte en tout temps ; si une interruption ou une r\u00e9sistance anormale est d\u00e9tect\u00e9e, cela peut indiquer des c\u00e2bles cass\u00e9s, des liaisons d\u00e9fectueuses ou des connexions desserr\u00e9es dues \u00e0 l&rsquo;impact. Dans ce cas, les connexions doivent \u00eatre r\u00e9par\u00e9es ou le tron\u00e7on de conducteur endommag\u00e9 remplac\u00e9 avant de remettre le syst\u00e8me en service<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Continuit\u00e9 \u00e9lectrique des conducteurs <\/strong><\/span><b>:<\/b><span style=\"font-weight: 400;\"> Il est indispensable de <strong>mesurer la r\u00e9sistance de la mise \u00e0 la terre<\/strong> du paratonnerre apr\u00e8s la chute d\u2019un coup de foudre. L\u2019efficacit\u00e9 du syst\u00e8me d\u00e9pend de la dissipation rapide du courant de foudre dans le sol, ce qui n\u00e9cessite g\u00e9n\u00e9ralement une r\u00e9sistance de terre faible. Dans la pratique, il est recommand\u00e9 que la valeur de r\u00e9sistance de terre soit <strong>inf\u00e9rieure \u00e0 10 \u03a9 (ohms).<\/strong> Apr\u00e8s un orage, cette valeur peut avoir vari\u00e9 (en raison de changements dans l&rsquo;humidit\u00e9 du sol, de la compaction, de dommages aux \u00e9lectrodes, etc.), il convient donc de la v\u00e9rifier avec un tellurom\u00e8tre. Il est id\u00e9al d&rsquo;utiliser la m\u00e9thode des trois pointes (m\u00e9thode de chute de potentiel) ou une autre m\u00e9thode approuv\u00e9e, en d\u00e9connectant temporairement la prise de terre principale pour la mesurer isol\u00e9ment. <strong>Si la r\u00e9sistance mesur\u00e9e d\u00e9passe la valeur recommand\u00e9e<\/strong>, il sera n\u00e9cessaire de prendre des mesures : par exemple, am\u00e9liorer le syst\u00e8me de terre en ajoutant plus <strong>d\u2019\u00e9lectrodes ou de piquets suppl\u00e9mentaires<\/strong>, en utilisant des additifs am\u00e9liorant la conductivit\u00e9 du sol, ou en v\u00e9rifiant les connexions des \u00e9lectrodes existantes. Dans les installations bien con\u00e7ues, le r\u00e9seau de terre comprend g\u00e9n\u00e9ralement des regards de visite ; il convient d\u2019en profiter pour v\u00e9rifier que les conducteurs et les jonctions aux piquets ne pr\u00e9sentent pas de corrosion ni de signes de surchauffe. L\u2019inspection p\u00e9riodique de la prise de terre est obligatoire dans de nombreux pays \u2013 <strong>au moins une fois par an \u2013 et toujours apr\u00e8s un impact de foudre<\/strong> significatif<\/span><\/li>\n<li><strong>V\u00e9rification des dispositifs de protection interne (DPS) <\/strong><b>:<\/b><span style=\"font-weight: 400;\"> Si l&rsquo;installation dispose de <strong>dispositifs de protection contre les surtensions (DPS)<\/strong> ou de parafoudres (dans le tableau \u00e9lectrique, sur les lignes de donn\u00e9es, etc.), ceux-ci doivent \u00eatre inspect\u00e9s apr\u00e8s l&rsquo;orage. M\u00eame si la foudre a \u00e9t\u00e9 intercept\u00e9e par le paratonnerre, cela n&#8217;emp\u00eache pas les champs \u00e9lectromagn\u00e9tiques d\u2019induire des surtensions dans les lignes. Les DPS sont con\u00e7us pour d\u00e9vier ces surtensions vers la terre, mais ils <strong>peuvent devenir inutilisables<\/strong> en le faisant. Il est important de v\u00e9rifier <strong>qu\u2019aucun DPS n\u2019indique un d\u00e9faut<\/strong>. Si un parafoudre montre un signe de d\u00e9faillance, il <strong>doit \u00eatre remplac\u00e9 imm\u00e9diatement<\/strong>, car il a perdu sa capacit\u00e9 \u00e0 prot\u00e9ger. Cette inspection technique garantit que la protection interne de l&rsquo;installation (\u00e9quipements \u00e9lectroniques, syst\u00e8mes de communication, appareils \u00e9lectrom\u00e9nagers, etc.) reste effective<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><strong>Syst\u00e8me d\u2019alertes et compteurs de foudre <\/strong><b>: Si un syst\u00e8me est install\u00e9, il est important de v\u00e9rifier <strong>le compteur de foudre<\/strong><span style=\"font-weight: 400;\">. Ces compteurs enregistrent le passage du courant de d\u00e9charge lors d\u2019un impact et leur lecture doit \u00eatre not\u00e9e pour avoir une trace de l\u2019\u00e9v\u00e9nement. De plus, certains syst\u00e8mes int\u00e8grent des enregistreurs intelligents tels que le <\/span><strong>SMART LIGHTNING LOGGER d\u2019Aplicaciones Tecnol\u00f3gicas S.A<\/strong><span style=\"font-weight: 400;\">., qui envoie des alertes en temps r\u00e9el lorsqu\u2019un coup de foudre impacte la structure. V\u00e9rifier que ces syst\u00e8mes d\u2019alarme et de monitoring fonctionnent (par exemple, signal de communication IoT actif, enregistrements stock\u00e9s correctement) assure que, \u00e0 l\u2019avenir, tout nouvel impact pourra \u00eatre d\u00e9tect\u00e9 et pris en charge rapidement.<\/span><\/b><\/li>\n<\/ul>\n<p><strong>En cas de d\u00e9gradation ou d\u2019anomalie d\u00e9tect\u00e9e, les r\u00e9parations n\u00e9cessaires doivent \u00eatre effectu\u00e9es d\u00e8s que possible<\/strong> pour r\u00e9tablir l\u2019efficacit\u00e9 du syst\u00e8me. Il n\u2019est pas acceptable de maintenir en service un paratonnerre avec des composants endommag\u00e9s, car lors d\u2019un prochain \u00e9v\u00e9nement, il pourrait \u00e9chouer dans sa fonction principale de prot\u00e9ger la structure o\u00f9 le syst\u00e8me est install\u00e9. Par exemple, une t\u00eate captrice partiellement fondue a des pointes \u00e9mouss\u00e9es qui peuvent affecter sa capacit\u00e9 \u00e0 capter le prochain coup de foudre ; un conducteur avec des sections r\u00e9duites par la chaleur peut ne pas conduire le courant correctement ; une prise de terre avec une r\u00e9sistance \u00e9lev\u00e9e peut provoquer des \u00e9tincelles dangereuses ou des d\u00e9rivations non souhait\u00e9es. Chaque composant doit \u00eatre, apr\u00e8s r\u00e9paration, <strong>dans des conditions \u00e9quivalentes aux originales de conception <\/strong>pour garantir la s\u00e9curit\u00e9<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Normes_et_reglementations_concernant_la_maintenance_des_systemes_de_protection_contre_la_foudre_apres_un_impact\"><\/span><b>Normes et r\u00e9glementations concernant la maintenance des syst\u00e8mes de protection contre la foudre apr\u00e8s un impact<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La <strong>r\u00e9glementation technique<\/strong>, tant internationale que nationale, \u00e9tablit la n\u00e9cessit\u00e9 <strong>d&rsquo;inspecter et d&rsquo;assurer la maintenance <\/strong>des syst\u00e8mes de protection contre la foudre de mani\u00e8re p\u00e9riodique, et <strong>tout particuli\u00e8rement apr\u00e8s une d\u00e9charge directe<\/strong> de la foudre. Parmi les plus pertinentes, on trouve :<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.une.org\/encuentra-tu-norma\/busca-tu-norma\/norma?c=N0048559\" target=\"_blank\" rel=\"noopener\">UNE 21186:2011<\/a> (Espagne) \u2013<\/strong> <em>Protection contre la foudre : Paratonnerres \u00e0 dispositif d&rsquo;amor\u00e7age<\/em><\/span><i><span style=\"font-weight: 400;\">.<\/span><\/i><span style=\"font-weight: 400;\"> Cette norme espagnole r\u00e9glemente la <strong>conception, l&rsquo;installation, la v\u00e9rification et la maintenance<\/strong> des installations \u00e9quip\u00e9es de paratonnerres \u00e0 dispositif d&rsquo;amor\u00e7age (PDA). Elle s&rsquo;applique fr\u00e9quemment aux b\u00e2timents o\u00f9 des paratonnerres actifs sont install\u00e9s, en Espagne ainsi que dans d&rsquo;autres pays. La norme UNE 21186 impose des v\u00e9rifications p\u00e9riodiques de ces syst\u00e8mes afin de garantir leur efficacit\u00e9 dans la protection des personnes et des biens, en d\u00e9taillant des proc\u00e9dures d\u2019inspection similaires \u00e0 celles d\u00e9crites (v\u00e9rification de la t\u00eate captrice du PDA, des conducteurs de descente, de la prise de terre, etc.). Apr\u00e8s un impact de foudre sur un paratonnerre PDA, la norme UNE 21186 indique qu\u2019un contr\u00f4le complet du syst\u00e8me doit \u00eatre r\u00e9alis\u00e9<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0<strong><a href=\"https:\/\/www.une.org\/encuentra-tu-norma\/busca-tu-norma\/norma?c=N0048407\" target=\"_blank\" rel=\"noopener\">S\u00e9rie UNE-EN IEC 62305<\/a> (Internationale) \u2013 <\/strong><em>Protection contre la foudre (Parties 1 \u00e0 4)<br \/>\n<\/em><\/span>Il s\u2019agit de l\u2019adoption nationale de la norme internationale <strong>IEC 62305<\/strong>. En particulier, la <strong>Partie 3 (UNE-EN 62305-3)<\/strong> traite de la protection des structures contre les dommages physiques et contient des exigences relatives \u00e0 l<strong>\u2019inspection et \u00e0 la maintenance <\/strong>des Syst\u00e8mes de Protection contre la Foudre (SPF). Cette norme stipule qu\u2019un SPF doit \u00eatre <strong>inspect\u00e9<\/strong> \u00e0 la fois p\u00e9riodiquement (en fonction du niveau de protection, voir ci-apr\u00e8s) et <strong>chaque fois qu\u2019il est suspect\u00e9 d\u2019avoir subi une d\u00e9charge<\/strong>. La <strong>Partie 4 (UNE-EN 62305-4)<\/strong> porte sur la protection des syst\u00e8mes \u00e9lectriques\/\u00e9lectroniques internes, et inclut \u00e9galement des directives de maintenance afin de garantir que les r\u00e9seaux de mise \u00e0 la terre et les dispositifs de protection contre les surtensions (DPS) demeurent en bon \u00e9tat.<br \/>\nConform\u00e9ment \u00e0 la norme IEC 62305, il est <strong>obligatoire de proc\u00e9der \u00e0 une v\u00e9rification de l\u2019installation apr\u00e8s tout impact de foudre connu sur la structure<\/strong>. Cette exigence se traduit notamment par la recommandation d\u2019installer des compteurs de coups de foudre, qui signalent ces d\u00e9charges.<\/li>\n<li><strong><a href=\"https:\/\/www.nfpa.org\/es\/codes-and-standards\/nfpa-780-standard-development\/780\" target=\"_blank\" rel=\"noopener\">NFPA 780<\/a> (\u00c9tats-Unis) <\/strong><em>Norme pour l&rsquo;installation des syst\u00e8mes de protection contre la foudre<\/em><i><span style=\"font-weight: 400;\">.<\/span><\/i><span style=\"font-weight: 400;\"><br \/>\nBien qu\u2019il s\u2019agisse d\u2019une norme am\u00e9ricaine, elle constitue une r\u00e9f\u00e9rence internationale. La NFPA 780 recommande des inspections p\u00e9riodiques des paratonnerres afin de garantir leur int\u00e9grit\u00e9. En particulier, elle sugg\u00e8re qu\u2019\u00e0 la suite de forts orages \u00e9lectriques ou de d\u00e9charges directes, une inspection exceptionnelle du syst\u00e8me soit effectu\u00e9e. Elle indique \u00e9galement qu&rsquo;une inspection doit avoir lieu apr\u00e8s toute modification de la structure prot\u00e9g\u00e9e ou si des composants endommag\u00e9s ont \u00e9t\u00e9 identifi\u00e9s. La philosophie de la NFPA 780 est pr\u00e9ventive : au minimum, une inspection visuelle annuelle et une v\u00e9rification compl\u00e8te tous les quelques ann\u00e9es, afin de garantir que le syst\u00e8me continue \u00e0 r\u00e9pondre \u00e0 la norme en vigueur. Bien que la NFPA 780 ne soit pas obligatoire en dehors des \u00c9tats-Unis, de nombreux de ses crit\u00e8res (par exemple : inspection apr\u00e8s un impact de foudre, continuit\u00e9 des conducteurs, utilisation de composants certifi\u00e9s\/list\u00e9s) sont consid\u00e9r\u00e9s comme de bonnes pratiques adopt\u00e9es \u00e0 l\u2019\u00e9chelle mondiale<br \/>\n<\/span><\/li>\n<li><strong>R\u00e9glementation espagnole et europ\u00e9enne compl\u00e9mentaire <\/strong><b>:<\/b><span style=\"font-weight: 400;\"> En Espagne, le <strong>Code Technique de la Construction (CTE)<\/strong>, dans son Document Fondamental SUA-8, \u00e9tablit la n\u00e9cessit\u00e9 de limiter le risque associ\u00e9 \u00e0 la foudre au moyen d\u2019installations appropri\u00e9es, ce qui implique \u00e9galement de maintenir ces installations en conditions de s\u00e9curit\u00e9. Le <strong>R\u00e8glement \u00c9lectrotechnique de Basse Tension (REBT)<\/strong> et ses guides techniques mentionnent la protection contre les surtensions et les d\u00e9rivations \u00e0 la terre, exigeant que les installations \u00e9lectriques (y compris les syst\u00e8mes de mise \u00e0 la terre) offrent un haut niveau de s\u00e9curit\u00e9 et soient correctement entretenues. De plus, il existe des normes europ\u00e9ennes sp\u00e9cifiques aux composants, comme la s\u00e9rie UNE-EN 62561, qui fixent les exigences relatives aux pi\u00e8ces de connexion, conducteurs, \u00e9lectrodes de terre, compteurs de coups de foudre, etc., assurant ainsi leur qualit\u00e9 et leur r\u00e9sistance aux d\u00e9charges. L\u2019ensemble de ces normes constitue un cadre r\u00e9glementaire qui <strong>souligne l\u2019importance de v\u00e9rifier que tous les \u00e9l\u00e9ments du Syst\u00e8me de Protection contre la Foudre (SPF) soient en bon \u00e9tat, par le biais d\u2019un entretien pr\u00e9ventif continu<\/strong>.<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><strong>Fr\u00e9quence des inspections selon le niveau de protection <\/strong>: Les normes techniques d\u00e9finissent souvent des intervalles maximaux entre les inspections. Par exemple, le guide de l\u2019IEC 62305 sugg\u00e8re que pour les syst\u00e8mes de niveau I ou II (risque \u00e9lev\u00e9), des <strong>inspections visuelles annuelles<\/strong> et des v\u00e9rifications compl\u00e8tes tous les deux ans soient r\u00e9alis\u00e9es, tandis que pour les niveaux III-IV, des inspections visuelles tous les deux ans et compl\u00e8tes tous les quatre ans sont admises. Cependant, <strong>apr\u00e8s un impact de foudre, ces inspections doivent \u00eatre imm\u00e9diatement anticip\u00e9es. <\/strong>Dans la pratique, de nombreuses normes nationales (y compris la norme espagnole) <strong>exigent au minimum une inspection annuelle, et syst\u00e9matiquement une apr\u00e8s tout impact de foudre ou apr\u00e8s toute modification structurelle<\/strong> du b\u00e2timent. Ne pas effectuer ces r\u00e9visions peut signifier que le syst\u00e8me ne respecte pas les conditions de s\u00e9curit\u00e9 requises, avec le risque cons\u00e9quent et d\u2019\u00e9ventuelles implications juridiques en cas de dommages caus\u00e9s par la foudre sur un syst\u00e8me n\u00e9gligemment entretenu<span style=\"font-weight: 400;\"><br \/>\n<\/span><\/li>\n<\/ul>\n<p>Pour toutes questions concernant la maintenance des paratonnerres ou les actions \u00e0 entreprendre apr\u00e8s un impact de foudre, vous pouvez nous contacter <a href=\"https:\/\/at3w.com\/fr\/ou-sommes-nous-contact\/\" target=\"_blank\" rel=\"noopener\">en cliquant ici<\/a>.<\/p>\n<p>Si vous le souhaitez, vous pouvez \u00e9galement assister \u00e0 l\u2019une de nos formations en ligne gratuites sur la protection contre la foudre, disponibles sur <a href=\"https:\/\/at3w.com\/fr\/formation-webinaires\/\" target=\"_blank\" rel=\"noopener\">notre page de webinaires<\/a>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div id=\"ultimate-heading-36406a97b6232d6ad\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-36406a97b6232d6ad uvc-4954 \" data-hspacer=\"line_only\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-36406a97b6232d6ad h2'  data-responsive-json-new='{\"font-size\":\"desktop:26px;\",\"line-height\":\"\"}' ><h2 style=\"font-family:&#039;Montserrat&#039;;font-weight:600;color:#243469;\"><span class=\"ez-toc-section\" id=\"Noticias_relacionadas\"><\/span>Noticias relacionadas<span class=\"ez-toc-section-end\"><\/span><\/h2><\/div><div class=\"uvc-heading-spacer line_only\" style=\"margin-top:1em;margin-bottom:1.3em;height:4px;\"><span class=\"uvc-headings-line\" style=\"border-style:solid;border-bottom-width:4px;border-color:#f7a800;width:60px;\"><\/span><\/div><\/div>[vc_basic_grid post_type=\u00a0\u00bbpost\u00a0\u00bb max_items=\u00a0\u00bb3&Prime; item=\u00a0\u00bb43456&Prime; grid_id=\u00a0\u00bbvc_gid:1753781403888-977869bd-ce71-3&Prime;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un syst\u00e8me de protection contre la foudre emp\u00eache qu\u2019un impact direct ne touche la structure, mais la d\u00e9charge frappe effectivement le paratonnerre. C\u2019est pourquoi, apr\u00e8s un impact, il est essentiel de v\u00e9rifier minutieusement l\u2019ensemble du syst\u00e8me de protection contre la foudre, car l\u2019int\u00e9grit\u00e9 de composants critiques (paratonnerre, conducteurs, connexions, prise de terre, etc.) peut \u00eatre compromise. Suivre un protocole post-impact garantit le bon fonctionnement du syst\u00e8me et le maintien de la protection de l\u2019installation.<\/p>\n","protected":false},"author":2,"featured_media":64281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[5570,5575,5550],"tags":[],"class_list":["post-64295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paratonnerres","category-protection-contre-les-surtensions","category-smart-lightning-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coup de foudre - Protocole apr\u00e8s un orage - AT3w<\/title>\n<meta name=\"description\" content=\"Que faire apr\u00e8s un coup de foudre ? Protocole d&#039;action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coup de foudre - Protocole apr\u00e8s un orage - AT3w\" \/>\n<meta property=\"og:description\" content=\"Que faire apr\u00e8s un coup de foudre ? Protocole d&#039;action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\" \/>\n<meta property=\"og:site_name\" content=\"Aplicaciones Tecnol\u00f3gicas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/APLICACIONES.TECNOLOGICAS\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T06:14:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aplicaciones Tecnol\u00f3gicas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aplicaciones Tecnol\u00f3gicas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\"},\"author\":{\"name\":\"Aplicaciones Tecnol\u00f3gicas\",\"@id\":\"https:\/\/at3w.com\/fr\/#\/schema\/person\/60f7ba90a83d3f79798cf3647ddddb8e\"},\"headline\":\"S\u00e9curit\u00e9 face aux orages \u2013 Que faire apr\u00e8s l&rsquo;impact de la foudre sur un paratonnerre ?\",\"datePublished\":\"2025-08-07T06:14:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\"},\"wordCount\":3485,\"publisher\":{\"@id\":\"https:\/\/at3w.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg\",\"articleSection\":[\"Paratonnerres Smart \u00e0 dispositif d\u2019amor\u00e7age\",\"Protection contre les surtensions\",\"SMART LIGHTNING\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\",\"url\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\",\"name\":\"Coup de foudre - Protocole apr\u00e8s un orage - AT3w\",\"isPartOf\":{\"@id\":\"https:\/\/at3w.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg\",\"datePublished\":\"2025-08-07T06:14:44+00:00\",\"description\":\"Que faire apr\u00e8s un coup de foudre ? Protocole d'action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage\",\"url\":\"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg\",\"contentUrl\":\"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg\",\"width\":1201,\"height\":629,\"caption\":\"coup-foudre-paratonnerre-s\u00e9curit\u00e9-orage-protocole-surtensions-r\u00e9glementation\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/at3w.com\/fr\/#website\",\"url\":\"https:\/\/at3w.com\/fr\/\",\"name\":\"Aplicaciones Tecnol\u00f3gicas\",\"description\":\"Smart Earthing Smart Lightning\",\"publisher\":{\"@id\":\"https:\/\/at3w.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/at3w.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/at3w.com\/fr\/#organization\",\"name\":\"Aplicaciones Tecnol\u00f3gicas\",\"url\":\"https:\/\/at3w.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/at3w.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/at3w.com\/wp-content\/uploads\/2019\/02\/LOGO-HOME-APLICACIONES-TECNOLOGICAS.svg\",\"contentUrl\":\"https:\/\/at3w.com\/wp-content\/uploads\/2019\/02\/LOGO-HOME-APLICACIONES-TECNOLOGICAS.svg\",\"width\":114,\"height\":104,\"caption\":\"Aplicaciones Tecnol\u00f3gicas\"},\"image\":{\"@id\":\"https:\/\/at3w.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/APLICACIONES.TECNOLOGICAS\/\",\"https:\/\/www.linkedin.com\/company\/aplicaciones-tecnologicas\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/at3w.com\/fr\/#\/schema\/person\/60f7ba90a83d3f79798cf3647ddddb8e\",\"name\":\"Aplicaciones Tecnol\u00f3gicas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/at3w.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c38deaac9e80722f3add9b01ade020323a0c3af3b38f60234cbcd687592bf9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c38deaac9e80722f3add9b01ade020323a0c3af3b38f60234cbcd687592bf9d?s=96&d=mm&r=g\",\"caption\":\"Aplicaciones Tecnol\u00f3gicas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coup de foudre - Protocole apr\u00e8s un orage - AT3w","description":"Que faire apr\u00e8s un coup de foudre ? Protocole d'action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/","og_locale":"fr_FR","og_type":"article","og_title":"Coup de foudre - Protocole apr\u00e8s un orage - AT3w","og_description":"Que faire apr\u00e8s un coup de foudre ? Protocole d'action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.","og_url":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/","og_site_name":"Aplicaciones Tecnol\u00f3gicas","article_publisher":"https:\/\/www.facebook.com\/APLICACIONES.TECNOLOGICAS\/","article_published_time":"2025-08-07T06:14:44+00:00","og_image":[{"width":1201,"height":629,"url":"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg","type":"image\/jpeg"}],"author":"Aplicaciones Tecnol\u00f3gicas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Aplicaciones Tecnol\u00f3gicas","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#article","isPartOf":{"@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/"},"author":{"name":"Aplicaciones Tecnol\u00f3gicas","@id":"https:\/\/at3w.com\/fr\/#\/schema\/person\/60f7ba90a83d3f79798cf3647ddddb8e"},"headline":"S\u00e9curit\u00e9 face aux orages \u2013 Que faire apr\u00e8s l&rsquo;impact de la foudre sur un paratonnerre ?","datePublished":"2025-08-07T06:14:44+00:00","mainEntityOfPage":{"@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/"},"wordCount":3485,"publisher":{"@id":"https:\/\/at3w.com\/fr\/#organization"},"image":{"@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage"},"thumbnailUrl":"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg","articleSection":["Paratonnerres Smart \u00e0 dispositif d\u2019amor\u00e7age","Protection contre les surtensions","SMART LIGHTNING"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/","url":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/","name":"Coup de foudre - Protocole apr\u00e8s un orage - AT3w","isPartOf":{"@id":"https:\/\/at3w.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage"},"image":{"@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage"},"thumbnailUrl":"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg","datePublished":"2025-08-07T06:14:44+00:00","description":"Que faire apr\u00e8s un coup de foudre ? Protocole d'action et r\u00e9glementations relatives aux paratonnerres et aux parafoudres conform\u00e9ment aux normes.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/at3w.com\/fr\/blog\/coup-foudre-paratonnerre-securite-orage-protocole-surtensions-reglementation\/#primaryimage","url":"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg","contentUrl":"https:\/\/at3w.com\/wp-content\/uploads\/seguridad-tormentas_PORTADA-FR.jpg","width":1201,"height":629,"caption":"coup-foudre-paratonnerre-s\u00e9curit\u00e9-orage-protocole-surtensions-r\u00e9glementation"},{"@type":"WebSite","@id":"https:\/\/at3w.com\/fr\/#website","url":"https:\/\/at3w.com\/fr\/","name":"Aplicaciones Tecnol\u00f3gicas","description":"Smart Earthing Smart Lightning","publisher":{"@id":"https:\/\/at3w.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/at3w.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/at3w.com\/fr\/#organization","name":"Aplicaciones Tecnol\u00f3gicas","url":"https:\/\/at3w.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/at3w.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/at3w.com\/wp-content\/uploads\/2019\/02\/LOGO-HOME-APLICACIONES-TECNOLOGICAS.svg","contentUrl":"https:\/\/at3w.com\/wp-content\/uploads\/2019\/02\/LOGO-HOME-APLICACIONES-TECNOLOGICAS.svg","width":114,"height":104,"caption":"Aplicaciones Tecnol\u00f3gicas"},"image":{"@id":"https:\/\/at3w.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/APLICACIONES.TECNOLOGICAS\/","https:\/\/www.linkedin.com\/company\/aplicaciones-tecnologicas\/"]},{"@type":"Person","@id":"https:\/\/at3w.com\/fr\/#\/schema\/person\/60f7ba90a83d3f79798cf3647ddddb8e","name":"Aplicaciones Tecnol\u00f3gicas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/at3w.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c38deaac9e80722f3add9b01ade020323a0c3af3b38f60234cbcd687592bf9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c38deaac9e80722f3add9b01ade020323a0c3af3b38f60234cbcd687592bf9d?s=96&d=mm&r=g","caption":"Aplicaciones Tecnol\u00f3gicas"}}]}},"_links":{"self":[{"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/posts\/64295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/comments?post=64295"}],"version-history":[{"count":5,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/posts\/64295\/revisions"}],"predecessor-version":[{"id":64299,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/posts\/64295\/revisions\/64299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/media\/64281"}],"wp:attachment":[{"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/media?parent=64295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/categories?post=64295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/at3w.com\/fr\/wp-json\/wp\/v2\/tags?post=64295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}